{"id":90184,"date":"2026-05-11T22:07:27","date_gmt":"2026-05-11T17:07:27","guid":{"rendered":"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/"},"modified":"2026-05-11T22:07:27","modified_gmt":"2026-05-11T17:07:27","slug":"digital-entrepreneurship-ewr2-2504-0008","status":"publish","type":"class","link":"https:\/\/www.psdf.org.pk\/ur\/class\/digital-entrepreneurship-ewr2-2504-0008\/","title":{"rendered":"Digital Entrepreneurship | EWR2-2504-0008"},"featured_media":0,"template":"","training_type":[],"districts_and_tehsils":[199,339],"sectors_and_subsectors":[517,505],"class_list":["post-90184","class","type-class","status-publish","hentry","districts_and_tehsils-lahore","districts_and_tehsils-lahore-lahore","sectors_and_subsectors-ict","sectors_and_subsectors-telecoms-ict"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Digital Entrepreneurship | EWR2-2504-0008 - PSDF<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digital Entrepreneurship | EWR2-2504-0008 - PSDF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/\" \/>\n<meta property=\"og:site_name\" content=\"PSDF\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/\",\"url\":\"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/\",\"name\":\"Digital Entrepreneurship | EWR2-2504-0008 - PSDF\",\"isPartOf\":{\"@id\":\"https:\/\/www.psdf.org.pk\/#website\"},\"datePublished\":\"2026-05-11T17:07:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/#breadcrumb\"},\"inLanguage\":\"ur\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.psdf.org.pk\/ur\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digital Entrepreneurship | EWR2-2504-0008\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.psdf.org.pk\/#website\",\"url\":\"https:\/\/www.psdf.org.pk\/\",\"name\":\"PSDF\",\"description\":\"Skills for Success\",\"publisher\":{\"@id\":\"https:\/\/www.psdf.org.pk\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.psdf.org.pk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ur\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.psdf.org.pk\/#organization\",\"name\":\"PSDF\",\"url\":\"https:\/\/www.psdf.org.pk\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ur\",\"@id\":\"https:\/\/www.psdf.org.pk\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.psdf.org.pk\/wp-content\/uploads\/2021\/08\/logo-2.png\",\"contentUrl\":\"https:\/\/www.psdf.org.pk\/wp-content\/uploads\/2021\/08\/logo-2.png\",\"width\":505,\"height\":638,\"caption\":\"PSDF\"},\"image\":{\"@id\":\"https:\/\/www.psdf.org.pk\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digital Entrepreneurship | EWR2-2504-0008 - PSDF","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Digital Entrepreneurship | EWR2-2504-0008 - PSDF","og_url":"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/","og_site_name":"PSDF","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/","url":"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/","name":"Digital Entrepreneurship | EWR2-2504-0008 - PSDF","isPartOf":{"@id":"https:\/\/www.psdf.org.pk\/#website"},"datePublished":"2026-05-11T17:07:27+00:00","breadcrumb":{"@id":"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/#breadcrumb"},"inLanguage":"ur","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.psdf.org.pk\/class\/digital-entrepreneurship-ewr2-2504-0008\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.psdf.org.pk\/ur\/home\/"},{"@type":"ListItem","position":2,"name":"Digital Entrepreneurship | EWR2-2504-0008"}]},{"@type":"WebSite","@id":"https:\/\/www.psdf.org.pk\/#website","url":"https:\/\/www.psdf.org.pk\/","name":"PSDF","description":"Skills for Success","publisher":{"@id":"https:\/\/www.psdf.org.pk\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.psdf.org.pk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ur"},{"@type":"Organization","@id":"https:\/\/www.psdf.org.pk\/#organization","name":"PSDF","url":"https:\/\/www.psdf.org.pk\/","logo":{"@type":"ImageObject","inLanguage":"ur","@id":"https:\/\/www.psdf.org.pk\/#\/schema\/logo\/image\/","url":"https:\/\/www.psdf.org.pk\/wp-content\/uploads\/2021\/08\/logo-2.png","contentUrl":"https:\/\/www.psdf.org.pk\/wp-content\/uploads\/2021\/08\/logo-2.png","width":505,"height":638,"caption":"PSDF"},"image":{"@id":"https:\/\/www.psdf.org.pk\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/class\/90184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/types\/class"}],"wp:attachment":[{"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/media?parent=90184"}],"wp:term":[{"taxonomy":"training_type","embeddable":true,"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/training_type?post=90184"},{"taxonomy":"districts_and_tehsils","embeddable":true,"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/districts_and_tehsils?post=90184"},{"taxonomy":"sectors_and_subsectors","embeddable":true,"href":"https:\/\/www.psdf.org.pk\/ur\/wp-json\/wp\/v2\/sectors_and_subsectors?post=90184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}